{"id":6911,"date":"2025-03-18T11:25:58","date_gmt":"2025-03-18T11:25:58","guid":{"rendered":"https:\/\/famase-facilitymanagement.com\/?p=6911"},"modified":"2026-06-29T16:49:43","modified_gmt":"2026-06-29T14:49:43","slug":"port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas","status":"publish","type":"post","link":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/","title":{"rendered":"PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-a-gestao-dos-riscos-psicossociais-deve-ser-continua-e-incluir-a-perspetiva-de-genero-dado-o-impacto-nas-condicoes-de-trabalho-a-iso-45003-2021-orienta-boas-praticas-para-um-ambiente-saudavel-prevenir-a-violencia-laboral-e-melhorar-o-bem-estar-impulsiona-produtividade-retencao-de-talento-e-imagem-organizacional\">A gest\u00e3o dos riscos psicossociais deve ser cont\u00ednua e incluir a perspetiva de g\u00e9nero, dado o impacto nas condi\u00e7\u00f5es de trabalho. A ISO 45003:2021 orienta boas pr\u00e1ticas para um ambiente saud\u00e1vel. Prevenir a viol\u00eancia laboral e melhorar o bem-estar impulsiona produtividade, reten\u00e7\u00e3o de talento e imagem organizacional.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A realidade das organiza\u00e7\u00f5es, nas suas avalia\u00e7\u00f5es de riscos psicossociais no trabalho, come\u00e7a a definir objetivos e indicadores rumo \u00e0 excel\u00eancia em mat\u00e9ria de seguran\u00e7a e sa\u00fade relativamente a este tipo de risco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A gest\u00e3o destes riscos psicossociais deve ser abordada numa l\u00f3gica de melhoria cont\u00ednua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Embora o n\u00famero de empresas que trabalham na melhoria das condi\u00e7\u00f5es organizacionais tenha aumentado, esta gest\u00e3o continua a ser <strong>um desafio no \u00e2mbito da preven\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atualmente, existem diferentes classifica\u00e7\u00f5es dos fatores psicossociais, tais como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conte\u00fado e caracter\u00edsticas do trabalho<\/li>\n\n\n\n<li>Carga e ritmo de trabalho<\/li>\n\n\n\n<li>Tempo de trabalho<\/li>\n\n\n\n<li>Participa\u00e7\u00e3o e controlo<\/li>\n\n\n\n<li>Cultura organizacional<\/li>\n\n\n\n<li>Ambiente e equipamentos de trabalho<\/li>\n\n\n\n<li>Rela\u00e7\u00f5es interpessoais no trabalho<\/li>\n\n\n\n<li>Papel na organiza\u00e7\u00e3o<\/li>\n\n\n\n<li>Desenvolvimento profissional<\/li>\n\n\n\n<li>Intera\u00e7\u00e3o entre vida pessoal e trabalho<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Fonte:<\/em><\/strong><em> Marco Europeu para a Gest\u00e3o do Risco Psicossocial (European Framework for Psychosocial Risk Management \u2013 PRIMA EF).<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"651\" height=\"649\" src=\"https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2025\/03\/ART-2-ccip-200625.jpg\" alt=\"\" class=\"wp-image-6914\" style=\"width:352px;height:auto\" srcset=\"https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2025\/03\/ART-2-ccip-200625.jpg 651w, https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2025\/03\/ART-2-ccip-200625-300x300.jpg 300w, https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2025\/03\/ART-2-ccip-200625-150x150.jpg 150w\" sizes=\"(max-width: 651px) 100vw, 651px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Em meados de 2021, foi publicada a tradu\u00e7\u00e3o oficial para portugu\u00eas da norma <strong>ISO 45003:2021 \u2013 <\/strong>Gest\u00e3o da seguran\u00e7a e sa\u00fade no trabalho \u2014 Seguran\u00e7a e sa\u00fade psicol\u00f3gica no trabalho \u2014 Diretrizes para a gest\u00e3o dos riscos psicossociais, <strong>a primeira norma internacional que fornece orienta\u00e7\u00f5es pr\u00e1ticas sobre a gest\u00e3o dos riscos psicossociais e a promo\u00e7\u00e3o do bem-estar no trabalho.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seja atrav\u00e9s da implementa\u00e7\u00e3o e\/ou certifica\u00e7\u00e3o ou seguindo os princ\u00edpios metodol\u00f3gicos desta norma, \u00e9 poss\u00edvel adotar uma abordagem estrat\u00e9gica para a gest\u00e3o dos riscos psicossociais a n\u00edvel organizacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 da responsabilidade das organiza\u00e7\u00f5es garantir um ambiente de trabalho seguro e saud\u00e1vel, que inclua tanto a prote\u00e7\u00e3o da sa\u00fade f\u00edsica como da sa\u00fade mental dos trabalhadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Os riscos psicossociais sob uma perspetiva de g\u00e9nero<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incorporar a <strong>perspetiva de g\u00e9nero<\/strong> na avalia\u00e7\u00e3o dos riscos e, em particular, dos riscos psicossociais, deve ser um objetivo priorit\u00e1rio nas rela\u00e7\u00f5es laborais. Isto porque as diferen\u00e7as de g\u00e9nero n\u00e3o afetam apenas as condi\u00e7\u00f5es de trabalho, mas tamb\u00e9m a exposi\u00e7\u00e3o aos riscos psicossociais.<strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A feminiza\u00e7\u00e3o de setores como a educa\u00e7\u00e3o, o apoio a pessoas dependentes e o servi\u00e7o dom\u00e9stico implica uma maior exposi\u00e7\u00e3o a fatores psicossociais.<strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viol\u00eancia e ass\u00e9dio no trabalho<strong>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No panorama internacional, a Conven\u00e7\u00e3o 190 da OIT estabelece um quadro abrangente para a prote\u00e7\u00e3o contra a viol\u00eancia e o ass\u00e9dio no trabalho. Este documento sublinha &#8220;<strong>a necessidade de uma abordagem inclusiva<\/strong> e integrada, que leve em conta as <strong>considera\u00e7\u00f5es de g\u00e9nero<\/strong> e aborde as causas subjacentes e os fatores de risco&#8221; (OIT, 2019).<strong> <\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ratifica\u00e7\u00e3o desta conven\u00e7\u00e3o por v\u00e1rios pa\u00edses, incluindo Portugal, refor\u00e7a a import\u00e2ncia da preven\u00e7\u00e3o ativa da viol\u00eancia e do ass\u00e9dio laboral como prioridade em mat\u00e9ria de sa\u00fade ocupacional.<strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Medir o impacto dos riscos psicossociais na sa\u00fade emocional n\u00e3o \u00e9 uma tarefa simples, sendo um desafio de longo prazo no qual as empresas devem investir para obter benef\u00edcios sustent\u00e1veis.<strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Redu\u00e7\u00e3o do absentismo laboral<\/li>\n\n\n\n<li>Cumprimento dos requisitos legais de preven\u00e7\u00e3o, incluindo <strong>protocolos contra ass\u00e9dio psicol\u00f3gico, sexual e\/ou por raz\u00e3o de g\u00e9nero<\/strong><\/li>\n\n\n\n<li>Aumento da produtividade<\/li>\n\n\n\n<li>Reten\u00e7\u00e3o de talento atrav\u00e9s do sal\u00e1rio emocional<\/li>\n\n\n\n<li>Redu\u00e7\u00e3o de erros causados por stress ou ansiedade<\/li>\n\n\n\n<li>Maior compromisso dos colaboradores com a organiza\u00e7\u00e3o<\/li>\n\n\n\n<li>Melhoria do ambiente de trabalho<\/li>\n\n\n\n<li>Refor\u00e7o da imagem da empresa, tanto para os trabalhadores como para os clientes<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Atualmente, torna-se essencial contar com bons servi\u00e7os de preven\u00e7\u00e3o, que, dentro do seu portef\u00f3lio de solu\u00e7\u00f5es, ajudem as organiza\u00e7\u00f5es a obter um diagn\u00f3stico realista da sua situa\u00e7\u00e3o em termos de <strong>investiga\u00e7\u00e3o e avalia\u00e7\u00e3o dos riscos psicossociais<\/strong>.<strong><\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Como dizia Albert Einstein: <\/strong><strong><em>&#8220;A preocupa\u00e7\u00e3o com o ser humano e a sua seguran\u00e7a deve ser sempre o principal objetivo de todos os esfor\u00e7os.&#8221;<\/em><\/strong><strong><\/strong><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-comecar-com-a-iso-4500\">Como come\u00e7ar com a ISO 4500<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<p class=\"wp-block-paragraph\">Quer pretenda utilizar a norma ISO 45003 dentro do seu sistema de gest\u00e3o de seguran\u00e7a e sa\u00fade no trabalho conforme \u00e0 ISO 45001 ou como um guia independente, o primeiro passo \u00e9 familiarizar-se com a norma e definir objetivos claros.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>FAMASE<\/strong> pode apoi\u00e1-lo desde as necessidades de forma\u00e7\u00e3o inicial at\u00e9 \u00e0 verifica\u00e7\u00e3o da conformidade atrav\u00e9s de uma Gap Analysis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contacte-nos!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A gest\u00e3o dos riscos psicossociais deve ser cont\u00ednua e incluir a perspetiva de g\u00e9nero, dado o impacto nas condi\u00e7\u00f5es de trabalho. A ISO 45003:2021 orienta boas pr\u00e1ticas para um ambiente saud\u00e1vel. Prevenir a viol\u00eancia laboral e melhorar o bem-estar impulsiona produtividade, reten\u00e7\u00e3o de talento e imagem organizacional. A realidade das organiza\u00e7\u00f5es, nas suas avalia\u00e7\u00f5es de riscos psicossociais no trabalho, come\u00e7a a definir objetivos e indicadores rumo \u00e0 excel\u00eancia em mat\u00e9ria de seguran\u00e7a e sa\u00fade relativamente a este tipo de risco. A gest\u00e3o destes riscos psicossociais deve ser abordada numa l\u00f3gica de melhoria cont\u00ednua. Embora o n\u00famero de empresas que trabalham na melhoria das condi\u00e7\u00f5es organizacionais tenha aumentado, esta gest\u00e3o continua a ser um desafio no \u00e2mbito da preven\u00e7\u00e3o. Atualmente, existem diferentes classifica\u00e7\u00f5es dos fatores psicossociais, tais como: Fonte: Marco Europeu para a Gest\u00e3o do Risco Psicossocial (European Framework for Psychosocial Risk Management \u2013 PRIMA EF). Em meados de 2021, foi publicada a tradu\u00e7\u00e3o oficial para portugu\u00eas da norma ISO 45003:2021 \u2013 Gest\u00e3o da seguran\u00e7a e sa\u00fade no trabalho \u2014 Seguran\u00e7a e sa\u00fade psicol\u00f3gica no trabalho \u2014 Diretrizes para a gest\u00e3o dos riscos psicossociais, a primeira norma internacional que fornece orienta\u00e7\u00f5es pr\u00e1ticas sobre a gest\u00e3o dos riscos psicossociais e a promo\u00e7\u00e3o do bem-estar no trabalho. Seja atrav\u00e9s da implementa\u00e7\u00e3o e\/ou certifica\u00e7\u00e3o ou seguindo os princ\u00edpios metodol\u00f3gicos desta norma, \u00e9 poss\u00edvel adotar uma abordagem estrat\u00e9gica para a gest\u00e3o dos riscos psicossociais a n\u00edvel organizacional. \u00c9 da responsabilidade das organiza\u00e7\u00f5es garantir um ambiente de trabalho seguro e saud\u00e1vel, que inclua tanto a prote\u00e7\u00e3o da sa\u00fade f\u00edsica como da sa\u00fade mental dos trabalhadores. Os riscos psicossociais sob uma perspetiva de g\u00e9nero Incorporar a perspetiva de g\u00e9nero na avalia\u00e7\u00e3o dos riscos e, em particular, dos riscos psicossociais, deve ser um objetivo priorit\u00e1rio nas rela\u00e7\u00f5es laborais. Isto porque as diferen\u00e7as de g\u00e9nero n\u00e3o afetam apenas as condi\u00e7\u00f5es de trabalho, mas tamb\u00e9m a exposi\u00e7\u00e3o aos riscos psicossociais. A feminiza\u00e7\u00e3o de setores como a educa\u00e7\u00e3o, o apoio a pessoas dependentes e o servi\u00e7o dom\u00e9stico implica uma maior exposi\u00e7\u00e3o a fatores psicossociais. Viol\u00eancia e ass\u00e9dio no trabalho. No panorama internacional, a Conven\u00e7\u00e3o 190 da OIT estabelece um quadro abrangente para a prote\u00e7\u00e3o contra a viol\u00eancia e o ass\u00e9dio no trabalho. Este documento sublinha &#8220;a necessidade de uma abordagem inclusiva e integrada, que leve em conta as considera\u00e7\u00f5es de g\u00e9nero e aborde as causas subjacentes e os fatores de risco&#8221; (OIT, 2019). A ratifica\u00e7\u00e3o desta conven\u00e7\u00e3o por v\u00e1rios pa\u00edses, incluindo Portugal, refor\u00e7a a import\u00e2ncia da preven\u00e7\u00e3o ativa da viol\u00eancia e do ass\u00e9dio laboral como prioridade em mat\u00e9ria de sa\u00fade ocupacional. Medir o impacto dos riscos psicossociais na sa\u00fade emocional n\u00e3o \u00e9 uma tarefa simples, sendo um desafio de longo prazo no qual as empresas devem investir para obter benef\u00edcios sustent\u00e1veis. Atualmente, torna-se essencial contar com bons servi\u00e7os de preven\u00e7\u00e3o, que, dentro do seu portef\u00f3lio de solu\u00e7\u00f5es, ajudem as organiza\u00e7\u00f5es a obter um diagn\u00f3stico realista da sua situa\u00e7\u00e3o em termos de investiga\u00e7\u00e3o e avalia\u00e7\u00e3o dos riscos psicossociais. Como dizia Albert Einstein: &#8220;A preocupa\u00e7\u00e3o com o ser humano e a sua seguran\u00e7a deve ser sempre o principal objetivo de todos os esfor\u00e7os.&#8221; Como come\u00e7ar com a ISO 4500 Quer pretenda utilizar a norma ISO 45003 dentro do seu sistema de gest\u00e3o de seguran\u00e7a e sa\u00fade no trabalho conforme \u00e0 ISO 45001 ou como um guia independente, o primeiro passo \u00e9 familiarizar-se com a norma e definir objetivos claros. A FAMASE pode apoi\u00e1-lo desde as necessidades de forma\u00e7\u00e3o inicial at\u00e9 \u00e0 verifica\u00e7\u00e3o da conformidade atrav\u00e9s de uma Gap Analysis. Contacte-nos!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[139,3],"tags":[37],"class_list":["post-6911","post","type-post","status-publish","format-standard","hentry","category-facility-management","category-agenda-2030","tag-home"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas - Famase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas - Famase\" \/>\n<meta property=\"og:description\" content=\"A gest\u00e3o dos riscos psicossociais deve ser cont\u00ednua e incluir a perspetiva de g\u00e9nero, dado o impacto nas condi\u00e7\u00f5es de trabalho. A ISO 45003:2021 orienta boas pr\u00e1ticas para um ambiente saud\u00e1vel. Prevenir a viol\u00eancia laboral e melhorar o bem-estar impulsiona produtividade, reten\u00e7\u00e3o de talento e imagem organizacional. A realidade das organiza\u00e7\u00f5es, nas suas avalia\u00e7\u00f5es de riscos psicossociais no trabalho, come\u00e7a a definir objetivos e indicadores rumo \u00e0 excel\u00eancia em mat\u00e9ria de seguran\u00e7a e sa\u00fade relativamente a este tipo de risco. A gest\u00e3o destes riscos psicossociais deve ser abordada numa l\u00f3gica de melhoria cont\u00ednua. Embora o n\u00famero de empresas que trabalham na melhoria das condi\u00e7\u00f5es organizacionais tenha aumentado, esta gest\u00e3o continua a ser um desafio no \u00e2mbito da preven\u00e7\u00e3o. Atualmente, existem diferentes classifica\u00e7\u00f5es dos fatores psicossociais, tais como: Fonte: Marco Europeu para a Gest\u00e3o do Risco Psicossocial (European Framework for Psychosocial Risk Management \u2013 PRIMA EF). Em meados de 2021, foi publicada a tradu\u00e7\u00e3o oficial para portugu\u00eas da norma ISO 45003:2021 \u2013 Gest\u00e3o da seguran\u00e7a e sa\u00fade no trabalho \u2014 Seguran\u00e7a e sa\u00fade psicol\u00f3gica no trabalho \u2014 Diretrizes para a gest\u00e3o dos riscos psicossociais, a primeira norma internacional que fornece orienta\u00e7\u00f5es pr\u00e1ticas sobre a gest\u00e3o dos riscos psicossociais e a promo\u00e7\u00e3o do bem-estar no trabalho. Seja atrav\u00e9s da implementa\u00e7\u00e3o e\/ou certifica\u00e7\u00e3o ou seguindo os princ\u00edpios metodol\u00f3gicos desta norma, \u00e9 poss\u00edvel adotar uma abordagem estrat\u00e9gica para a gest\u00e3o dos riscos psicossociais a n\u00edvel organizacional. \u00c9 da responsabilidade das organiza\u00e7\u00f5es garantir um ambiente de trabalho seguro e saud\u00e1vel, que inclua tanto a prote\u00e7\u00e3o da sa\u00fade f\u00edsica como da sa\u00fade mental dos trabalhadores. Os riscos psicossociais sob uma perspetiva de g\u00e9nero Incorporar a perspetiva de g\u00e9nero na avalia\u00e7\u00e3o dos riscos e, em particular, dos riscos psicossociais, deve ser um objetivo priorit\u00e1rio nas rela\u00e7\u00f5es laborais. Isto porque as diferen\u00e7as de g\u00e9nero n\u00e3o afetam apenas as condi\u00e7\u00f5es de trabalho, mas tamb\u00e9m a exposi\u00e7\u00e3o aos riscos psicossociais. A feminiza\u00e7\u00e3o de setores como a educa\u00e7\u00e3o, o apoio a pessoas dependentes e o servi\u00e7o dom\u00e9stico implica uma maior exposi\u00e7\u00e3o a fatores psicossociais. Viol\u00eancia e ass\u00e9dio no trabalho. No panorama internacional, a Conven\u00e7\u00e3o 190 da OIT estabelece um quadro abrangente para a prote\u00e7\u00e3o contra a viol\u00eancia e o ass\u00e9dio no trabalho. Este documento sublinha &#8220;a necessidade de uma abordagem inclusiva e integrada, que leve em conta as considera\u00e7\u00f5es de g\u00e9nero e aborde as causas subjacentes e os fatores de risco&#8221; (OIT, 2019). A ratifica\u00e7\u00e3o desta conven\u00e7\u00e3o por v\u00e1rios pa\u00edses, incluindo Portugal, refor\u00e7a a import\u00e2ncia da preven\u00e7\u00e3o ativa da viol\u00eancia e do ass\u00e9dio laboral como prioridade em mat\u00e9ria de sa\u00fade ocupacional. Medir o impacto dos riscos psicossociais na sa\u00fade emocional n\u00e3o \u00e9 uma tarefa simples, sendo um desafio de longo prazo no qual as empresas devem investir para obter benef\u00edcios sustent\u00e1veis. Atualmente, torna-se essencial contar com bons servi\u00e7os de preven\u00e7\u00e3o, que, dentro do seu portef\u00f3lio de solu\u00e7\u00f5es, ajudem as organiza\u00e7\u00f5es a obter um diagn\u00f3stico realista da sua situa\u00e7\u00e3o em termos de investiga\u00e7\u00e3o e avalia\u00e7\u00e3o dos riscos psicossociais. Como dizia Albert Einstein: &#8220;A preocupa\u00e7\u00e3o com o ser humano e a sua seguran\u00e7a deve ser sempre o principal objetivo de todos os esfor\u00e7os.&#8221; Como come\u00e7ar com a ISO 4500 Quer pretenda utilizar a norma ISO 45003 dentro do seu sistema de gest\u00e3o de seguran\u00e7a e sa\u00fade no trabalho conforme \u00e0 ISO 45001 ou como um guia independente, o primeiro passo \u00e9 familiarizar-se com a norma e definir objetivos claros. A FAMASE pode apoi\u00e1-lo desde as necessidades de forma\u00e7\u00e3o inicial at\u00e9 \u00e0 verifica\u00e7\u00e3o da conformidade atrav\u00e9s de uma Gap Analysis. Contacte-nos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/\" \/>\n<meta property=\"og:site_name\" content=\"Famase\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-18T11:25:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T14:49:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2025\/03\/ART-2-ccip-200625.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"651\" \/>\n\t<meta property=\"og:image:height\" content=\"649\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dissenyador famase 2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FamaseFm\" \/>\n<meta name=\"twitter:site\" content=\"@FamaseFm\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"dissenyador famase 2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/\"},\"author\":{\"name\":\"dissenyador famase 2\",\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/#\\\/schema\\\/person\\\/9ed8426d7859602c40726494afd67a9f\"},\"headline\":\"PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas\",\"datePublished\":\"2025-03-18T11:25:58+00:00\",\"dateModified\":\"2026-06-29T14:49:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/\"},\"wordCount\":807,\"publisher\":{\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ART-2-ccip-200625.jpg\",\"keywords\":[\"Home\"],\"articleSection\":[\"Facility Management\",\"Sostenibilidad - Agenda 2030\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/\",\"url\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/\",\"name\":\"PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas - Famase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ART-2-ccip-200625.jpg\",\"datePublished\":\"2025-03-18T11:25:58+00:00\",\"dateModified\":\"2026-06-29T14:49:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ART-2-ccip-200625.jpg\",\"contentUrl\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ART-2-ccip-200625.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/2025\\\/03\\\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/\",\"name\":\"Famase\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/#organization\",\"name\":\"Famase\",\"url\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logotip_Famase_positiu-scaled-e1778663694259.png\",\"contentUrl\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Logotip_Famase_positiu-scaled-e1778663694259.png\",\"width\":2086,\"height\":700,\"caption\":\"Famase\"},\"image\":{\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/FamaseFm\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/facility-management-and-services\\\/?originalSubdomain=es\",\"https:\\\/\\\/www.instagram.com\\\/famasefacility\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/#\\\/schema\\\/person\\\/9ed8426d7859602c40726494afd67a9f\",\"name\":\"dissenyador famase 2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca7a3ef4628187986127dfeef6a27e6d597f7d349d536b496696e99e2876028c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca7a3ef4628187986127dfeef6a27e6d597f7d349d536b496696e99e2876028c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca7a3ef4628187986127dfeef6a27e6d597f7d349d536b496696e99e2876028c?s=96&d=mm&r=g\",\"caption\":\"dissenyador famase 2\"},\"sameAs\":[\"https:\\\/\\\/famase-facilitymanagement.com\"],\"url\":\"https:\\\/\\\/famase-facilitymanagement.com\\\/en\\\/author\\\/dissenyador-famase-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas - Famase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/","og_locale":"en_US","og_type":"article","og_title":"PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas - Famase","og_description":"A gest\u00e3o dos riscos psicossociais deve ser cont\u00ednua e incluir a perspetiva de g\u00e9nero, dado o impacto nas condi\u00e7\u00f5es de trabalho. A ISO 45003:2021 orienta boas pr\u00e1ticas para um ambiente saud\u00e1vel. Prevenir a viol\u00eancia laboral e melhorar o bem-estar impulsiona produtividade, reten\u00e7\u00e3o de talento e imagem organizacional. A realidade das organiza\u00e7\u00f5es, nas suas avalia\u00e7\u00f5es de riscos psicossociais no trabalho, come\u00e7a a definir objetivos e indicadores rumo \u00e0 excel\u00eancia em mat\u00e9ria de seguran\u00e7a e sa\u00fade relativamente a este tipo de risco. A gest\u00e3o destes riscos psicossociais deve ser abordada numa l\u00f3gica de melhoria cont\u00ednua. Embora o n\u00famero de empresas que trabalham na melhoria das condi\u00e7\u00f5es organizacionais tenha aumentado, esta gest\u00e3o continua a ser um desafio no \u00e2mbito da preven\u00e7\u00e3o. Atualmente, existem diferentes classifica\u00e7\u00f5es dos fatores psicossociais, tais como: Fonte: Marco Europeu para a Gest\u00e3o do Risco Psicossocial (European Framework for Psychosocial Risk Management \u2013 PRIMA EF). Em meados de 2021, foi publicada a tradu\u00e7\u00e3o oficial para portugu\u00eas da norma ISO 45003:2021 \u2013 Gest\u00e3o da seguran\u00e7a e sa\u00fade no trabalho \u2014 Seguran\u00e7a e sa\u00fade psicol\u00f3gica no trabalho \u2014 Diretrizes para a gest\u00e3o dos riscos psicossociais, a primeira norma internacional que fornece orienta\u00e7\u00f5es pr\u00e1ticas sobre a gest\u00e3o dos riscos psicossociais e a promo\u00e7\u00e3o do bem-estar no trabalho. Seja atrav\u00e9s da implementa\u00e7\u00e3o e\/ou certifica\u00e7\u00e3o ou seguindo os princ\u00edpios metodol\u00f3gicos desta norma, \u00e9 poss\u00edvel adotar uma abordagem estrat\u00e9gica para a gest\u00e3o dos riscos psicossociais a n\u00edvel organizacional. \u00c9 da responsabilidade das organiza\u00e7\u00f5es garantir um ambiente de trabalho seguro e saud\u00e1vel, que inclua tanto a prote\u00e7\u00e3o da sa\u00fade f\u00edsica como da sa\u00fade mental dos trabalhadores. Os riscos psicossociais sob uma perspetiva de g\u00e9nero Incorporar a perspetiva de g\u00e9nero na avalia\u00e7\u00e3o dos riscos e, em particular, dos riscos psicossociais, deve ser um objetivo priorit\u00e1rio nas rela\u00e7\u00f5es laborais. Isto porque as diferen\u00e7as de g\u00e9nero n\u00e3o afetam apenas as condi\u00e7\u00f5es de trabalho, mas tamb\u00e9m a exposi\u00e7\u00e3o aos riscos psicossociais. A feminiza\u00e7\u00e3o de setores como a educa\u00e7\u00e3o, o apoio a pessoas dependentes e o servi\u00e7o dom\u00e9stico implica uma maior exposi\u00e7\u00e3o a fatores psicossociais. Viol\u00eancia e ass\u00e9dio no trabalho. No panorama internacional, a Conven\u00e7\u00e3o 190 da OIT estabelece um quadro abrangente para a prote\u00e7\u00e3o contra a viol\u00eancia e o ass\u00e9dio no trabalho. Este documento sublinha &#8220;a necessidade de uma abordagem inclusiva e integrada, que leve em conta as considera\u00e7\u00f5es de g\u00e9nero e aborde as causas subjacentes e os fatores de risco&#8221; (OIT, 2019). A ratifica\u00e7\u00e3o desta conven\u00e7\u00e3o por v\u00e1rios pa\u00edses, incluindo Portugal, refor\u00e7a a import\u00e2ncia da preven\u00e7\u00e3o ativa da viol\u00eancia e do ass\u00e9dio laboral como prioridade em mat\u00e9ria de sa\u00fade ocupacional. Medir o impacto dos riscos psicossociais na sa\u00fade emocional n\u00e3o \u00e9 uma tarefa simples, sendo um desafio de longo prazo no qual as empresas devem investir para obter benef\u00edcios sustent\u00e1veis. Atualmente, torna-se essencial contar com bons servi\u00e7os de preven\u00e7\u00e3o, que, dentro do seu portef\u00f3lio de solu\u00e7\u00f5es, ajudem as organiza\u00e7\u00f5es a obter um diagn\u00f3stico realista da sua situa\u00e7\u00e3o em termos de investiga\u00e7\u00e3o e avalia\u00e7\u00e3o dos riscos psicossociais. Como dizia Albert Einstein: &#8220;A preocupa\u00e7\u00e3o com o ser humano e a sua seguran\u00e7a deve ser sempre o principal objetivo de todos os esfor\u00e7os.&#8221; Como come\u00e7ar com a ISO 4500 Quer pretenda utilizar a norma ISO 45003 dentro do seu sistema de gest\u00e3o de seguran\u00e7a e sa\u00fade no trabalho conforme \u00e0 ISO 45001 ou como um guia independente, o primeiro passo \u00e9 familiarizar-se com a norma e definir objetivos claros. A FAMASE pode apoi\u00e1-lo desde as necessidades de forma\u00e7\u00e3o inicial at\u00e9 \u00e0 verifica\u00e7\u00e3o da conformidade atrav\u00e9s de uma Gap Analysis. Contacte-nos!","og_url":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/","og_site_name":"Famase","article_published_time":"2025-03-18T11:25:58+00:00","article_modified_time":"2026-06-29T14:49:43+00:00","og_image":[{"width":651,"height":649,"url":"https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2025\/03\/ART-2-ccip-200625.jpg","type":"image\/jpeg"}],"author":"dissenyador famase 2","twitter_card":"summary_large_image","twitter_creator":"@FamaseFm","twitter_site":"@FamaseFm","twitter_misc":{"Written by":"dissenyador famase 2","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/#article","isPartOf":{"@id":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/"},"author":{"name":"dissenyador famase 2","@id":"https:\/\/famase-facilitymanagement.com\/en\/#\/schema\/person\/9ed8426d7859602c40726494afd67a9f"},"headline":"PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas","datePublished":"2025-03-18T11:25:58+00:00","dateModified":"2026-06-29T14:49:43+00:00","mainEntityOfPage":{"@id":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/"},"wordCount":807,"publisher":{"@id":"https:\/\/famase-facilitymanagement.com\/en\/#organization"},"image":{"@id":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2025\/03\/ART-2-ccip-200625.jpg","keywords":["Home"],"articleSection":["Facility Management","Sostenibilidad - Agenda 2030"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/","url":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/","name":"PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas - Famase","isPartOf":{"@id":"https:\/\/famase-facilitymanagement.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/#primaryimage"},"image":{"@id":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2025\/03\/ART-2-ccip-200625.jpg","datePublished":"2025-03-18T11:25:58+00:00","dateModified":"2026-06-29T14:49:43+00:00","breadcrumb":{"@id":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/#primaryimage","url":"https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2025\/03\/ART-2-ccip-200625.jpg","contentUrl":"https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2025\/03\/ART-2-ccip-200625.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/famase-facilitymanagement.com\/en\/2025\/03\/port-impulsionar-a-gestao-dos-riscos-psicossociais-com-perspetiva-de-genero-nas-empresas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/famase-facilitymanagement.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"PORT \u25ba ISO 45003:2021 Impulsionar a gest\u00e3o dos riscos psicossociais com perspetiva de g\u00e9nero nas empresas"}]},{"@type":"WebSite","@id":"https:\/\/famase-facilitymanagement.com\/en\/#website","url":"https:\/\/famase-facilitymanagement.com\/en\/","name":"Famase","description":"","publisher":{"@id":"https:\/\/famase-facilitymanagement.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/famase-facilitymanagement.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/famase-facilitymanagement.com\/en\/#organization","name":"Famase","url":"https:\/\/famase-facilitymanagement.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/famase-facilitymanagement.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2024\/05\/Logotip_Famase_positiu-scaled-e1778663694259.png","contentUrl":"https:\/\/famase-facilitymanagement.com\/wp-content\/uploads\/2024\/05\/Logotip_Famase_positiu-scaled-e1778663694259.png","width":2086,"height":700,"caption":"Famase"},"image":{"@id":"https:\/\/famase-facilitymanagement.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/FamaseFm","https:\/\/www.linkedin.com\/company\/facility-management-and-services\/?originalSubdomain=es","https:\/\/www.instagram.com\/famasefacility\/"]},{"@type":"Person","@id":"https:\/\/famase-facilitymanagement.com\/en\/#\/schema\/person\/9ed8426d7859602c40726494afd67a9f","name":"dissenyador famase 2","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ca7a3ef4628187986127dfeef6a27e6d597f7d349d536b496696e99e2876028c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca7a3ef4628187986127dfeef6a27e6d597f7d349d536b496696e99e2876028c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca7a3ef4628187986127dfeef6a27e6d597f7d349d536b496696e99e2876028c?s=96&d=mm&r=g","caption":"dissenyador famase 2"},"sameAs":["https:\/\/famase-facilitymanagement.com"],"url":"https:\/\/famase-facilitymanagement.com\/en\/author\/dissenyador-famase-2\/"}]}},"_links":{"self":[{"href":"https:\/\/famase-facilitymanagement.com\/en\/wp-json\/wp\/v2\/posts\/6911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/famase-facilitymanagement.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/famase-facilitymanagement.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/famase-facilitymanagement.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/famase-facilitymanagement.com\/en\/wp-json\/wp\/v2\/comments?post=6911"}],"version-history":[{"count":1,"href":"https:\/\/famase-facilitymanagement.com\/en\/wp-json\/wp\/v2\/posts\/6911\/revisions"}],"predecessor-version":[{"id":7818,"href":"https:\/\/famase-facilitymanagement.com\/en\/wp-json\/wp\/v2\/posts\/6911\/revisions\/7818"}],"wp:attachment":[{"href":"https:\/\/famase-facilitymanagement.com\/en\/wp-json\/wp\/v2\/media?parent=6911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/famase-facilitymanagement.com\/en\/wp-json\/wp\/v2\/categories?post=6911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/famase-facilitymanagement.com\/en\/wp-json\/wp\/v2\/tags?post=6911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}